{"id":10436,"date":"2023-01-09T15:31:36","date_gmt":"2023-01-09T14:31:36","guid":{"rendered":"https:\/\/www.bocedisrl.com\/news\/indian-ceramics-asia-2023\/"},"modified":"2023-01-12T14:13:46","modified_gmt":"2023-01-12T13:13:46","slug":"indian-ceramics-asia-2023","status":"publish","type":"post","link":"https:\/\/bocedisrl.com\/it\/news\/eventi\/indian-ceramics-asia-2023\/","title":{"rendered":"Indian Ceramics Asia 2023"},"content":{"rendered":"\n<p>L&#8217;industria ceramica indiana ha il potenziale per diventare il pi\u00f9 grande produttore al mondo, in quanto intende quasi raddoppiare il proprio fatturato entro il 2024. La crescita del settore \u00e8 trainata principalmente dall&#8217;aumento della domanda di piastrelle in ceramica, sanitari, tubi, ecc. per le applicazioni edilizie in India e per le esportazioni verso gli Stati Uniti, l&#8217;Europa, il Medio Oriente e altre destinazioni pi\u00f9 recenti.<\/p>\n\n\n\n<p>Indian Ceramics Asia \u00e8 una fiera globale ed una conferenza annuale per l&#8217;industria della ceramica e dei laterizi che attira i principali operatori di tutto il mondo alla ricerca di maggiore competitivit\u00e0, efficienza produttiva, ultime tendenze e innovazioni tecnologiche, nonch\u00e9 sostenibilit\u00e0 ambientale.<\/p>\n\n\n\n<p>All&#8217;Indian Ceramic Asia di Gandhinagar-Gujarat INDIA _dal 15 al 17 febbraio 2023_ esporremo la nostra esperienza e il nostro know-how nelle linee di packaging completamente aromatizzate per : &nbsp;piastrelle, sanitari e laterizi in ceramica.<\/p>\n\n\n\n<p>In qualit\u00e0 di&nbsp;<strong>produttore leader di sistemi di confezionamento di fine linea<\/strong>, offriamo soluzioni d\u2019imballo chiavi in mano progettate in base alle esigenze del cliente.<\/p>\n\n\n\n<p>Il nostro portafoglio di prodotti per il packaging automatizzato comprende macchine &nbsp;a&nbsp;<strong>cappuccio termoretraibile<\/strong>&nbsp;e macchine a&nbsp;<strong>cappuccio elastico<\/strong>. Offriamo un&#8217;ampia gamma di macchine con diverse capacit\u00e0 produttive per soddisfare i cicli di confezionamento pi\u00f9 impegnativi.<\/p>\n\n\n\n<p>Da oltre 45 anni serviamo l&#8217;industria delle piastrelle e dei mattoni, offrendo linee di confezionamento completamente automatizzate ad alte prestazioni,&nbsp;<strong>facili da gestire e da mantenere<\/strong>.&nbsp;&nbsp;<\/p>\n\n\n\n<p>I migliori produttori del settore in tutto il mondo hanno scelto la nostra tecnologia di confezionamento con cappuccio estensibile o termoretraibile perch\u00e9 i carichi ottengono una superiore stabilit\u00e0 , un imballaggio adatto all&#8217;esportazione, una protezione totale dagli agenti atmosferici e dalla polvere, una protezione dai raggi UV e un&#8217;eccezionale esposizione del prodotto.&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>Se state pianificando una visita all\u2019Indian Ceramics Asia a Gandhinagar-Gujarat INDIA, venite a visitare il nostro stand nella <strong>Hall 2 \u2013 C221a<\/strong>.<\/p>\n\n\n\n<p>Prenotate un appuntamento con il nostro team sullo stand:<\/p>\n\n\n\n<p><strong>Mr Cristian Bocedi _ Export Sales Manager&nbsp;<a href=\"mailto:cristianbocedi@bocedisrl.com\" target=\"_blank\" rel=\"noreferrer noopener\">cristianbocedi@bocedisrl.com<\/a><\/strong><strong><\/strong><\/p>\n\n\n\n<p><strong>Mr Riccardo Costi _ Project Manager&nbsp;<a href=\"mailto:riccardocosti@bocedisrl.com\" target=\"_blank\" rel=\"noreferrer noopener\">riccardocosti@bocedisrl.com<\/a><\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-1 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Bocedi stretch hood packaging Fully automated packaging lines for ceramic tiles\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/V8WCQHbjuqk?start=1&#038;feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Bocedi strapping and shrink hood wrapping   Turn key packaging line for ceramic tiles\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/VWDodJHFEDE?start=5&#038;feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;industria ceramica indiana ha il potenziale per diventare il pi\u00f9 grande produttore al mondo, in quanto intende quasi raddoppiare il proprio fatturato entro il 2024. La crescita del settore \u00e8 trainata principalmente dall&#8217;aumento della domanda di piastrelle in ceramica, sanitari, tubi, ecc. per le applicazioni edilizie in India e per le esportazioni verso gli Stati [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":10434,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[32],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Indian Ceramics Asia 2023 - Bocedi srl<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bocedisrl.com\/it\/news\/eventi\/indian-ceramics-asia-2023\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Indian Ceramics Asia 2023 - Bocedi srl\" \/>\n<meta property=\"og:description\" content=\"L&#8217;industria ceramica indiana ha il potenziale per diventare il pi\u00f9 grande produttore al mondo, in quanto intende quasi raddoppiare il proprio fatturato entro il 2024. La crescita del settore \u00e8 trainata principalmente dall&#8217;aumento della domanda di piastrelle in ceramica, sanitari, tubi, ecc. per le applicazioni edilizie in India e per le esportazioni verso gli Stati [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bocedisrl.com\/it\/news\/eventi\/indian-ceramics-asia-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Bocedi srl\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-09T14:31:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-12T13:13:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/STRETCHHOOD.IT\/wp-content\/uploads\/2023\/01\/indian-ceramics-asia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1028\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marco Iori\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marco Iori\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/bocedisrl.com\/it\/news\/eventi\/indian-ceramics-asia-2023\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/bocedisrl.com\/it\/news\/eventi\/indian-ceramics-asia-2023\/\"},\"author\":{\"name\":\"Marco Iori\",\"@id\":\"https:\/\/STRETCHHOOD.IT\/fr\/#\/schema\/person\/bf2baf56b280f94948de40b1612eae19\"},\"headline\":\"Indian Ceramics Asia 2023\",\"datePublished\":\"2023-01-09T14:31:36+00:00\",\"dateModified\":\"2023-01-12T13:13:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/bocedisrl.com\/it\/news\/eventi\/indian-ceramics-asia-2023\/\"},\"wordCount\":358,\"publisher\":{\"@id\":\"https:\/\/STRETCHHOOD.IT\/fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/bocedisrl.com\/it\/news\/eventi\/indian-ceramics-asia-2023\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/bocedisrl.com\/wp-content\/uploads\/2023\/01\/indian-ceramics-asia.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bocedisrl.com\/it\/news\/eventi\/indian-ceramics-asia-2023\/\",\"url\":\"https:\/\/bocedisrl.com\/it\/news\/eventi\/indian-ceramics-asia-2023\/\",\"name\":\"Indian Ceramics Asia 2023 - Bocedi srl\",\"isPartOf\":{\"@id\":\"https:\/\/STRETCHHOOD.IT\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/bocedisrl.com\/it\/news\/eventi\/indian-ceramics-asia-2023\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/bocedisrl.com\/it\/news\/eventi\/indian-ceramics-asia-2023\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/bocedisrl.com\/wp-content\/uploads\/2023\/01\/indian-ceramics-asia.jpg\",\"datePublished\":\"2023-01-09T14:31:36+00:00\",\"dateModified\":\"2023-01-12T13:13:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/bocedisrl.com\/it\/news\/eventi\/indian-ceramics-asia-2023\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bocedisrl.com\/it\/news\/eventi\/indian-ceramics-asia-2023\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/bocedisrl.com\/it\/news\/eventi\/indian-ceramics-asia-2023\/#primaryimage\",\"url\":\"https:\/\/bocedisrl.com\/wp-content\/uploads\/2023\/01\/indian-ceramics-asia.jpg\",\"contentUrl\":\"https:\/\/bocedisrl.com\/wp-content\/uploads\/2023\/01\/indian-ceramics-asia.jpg\",\"width\":1028,\"height\":627},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bocedisrl.com\/it\/news\/eventi\/indian-ceramics-asia-2023\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/STRETCHHOOD.IT\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\/\/bocedisrl.com\/it\/category\/news\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Eventi\",\"item\":\"https:\/\/bocedisrl.com\/it\/category\/news\/eventi\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Indian Ceramics Asia 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/STRETCHHOOD.IT\/fr\/#website\",\"url\":\"https:\/\/STRETCHHOOD.IT\/fr\/\",\"name\":\"Bocedi srl\",\"description\":\"Pallet Packaging Systems\",\"publisher\":{\"@id\":\"https:\/\/STRETCHHOOD.IT\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/STRETCHHOOD.IT\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/STRETCHHOOD.IT\/fr\/#organization\",\"name\":\"Bocedi srl\",\"url\":\"https:\/\/STRETCHHOOD.IT\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/STRETCHHOOD.IT\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.bocedisrl.com\/wp-content\/uploads\/2021\/11\/logo-bocedi.png\",\"contentUrl\":\"https:\/\/www.bocedisrl.com\/wp-content\/uploads\/2021\/11\/logo-bocedi.png\",\"width\":800,\"height\":480,\"caption\":\"Bocedi srl\"},\"image\":{\"@id\":\"https:\/\/STRETCHHOOD.IT\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/STRETCHHOOD.IT\/fr\/#\/schema\/person\/bf2baf56b280f94948de40b1612eae19\",\"name\":\"Marco Iori\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/STRETCHHOOD.IT\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/619eb84d8815ffd55f76c8c96d01893a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/619eb84d8815ffd55f76c8c96d01893a?s=96&d=mm&r=g\",\"caption\":\"Marco Iori\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Indian Ceramics Asia 2023 - Bocedi srl","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bocedisrl.com\/it\/news\/eventi\/indian-ceramics-asia-2023\/","og_locale":"it_IT","og_type":"article","og_title":"Indian Ceramics Asia 2023 - Bocedi srl","og_description":"L&#8217;industria ceramica indiana ha il potenziale per diventare il pi\u00f9 grande produttore al mondo, in quanto intende quasi raddoppiare il proprio fatturato entro il 2024. La crescita del settore \u00e8 trainata principalmente dall&#8217;aumento della domanda di piastrelle in ceramica, sanitari, tubi, ecc. per le applicazioni edilizie in India e per le esportazioni verso gli Stati [&hellip;]","og_url":"https:\/\/bocedisrl.com\/it\/news\/eventi\/indian-ceramics-asia-2023\/","og_site_name":"Bocedi srl","article_published_time":"2023-01-09T14:31:36+00:00","article_modified_time":"2023-01-12T13:13:46+00:00","og_image":[{"width":1028,"height":627,"url":"https:\/\/STRETCHHOOD.IT\/wp-content\/uploads\/2023\/01\/indian-ceramics-asia.jpg","type":"image\/jpeg"}],"author":"Marco Iori","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Marco Iori","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bocedisrl.com\/it\/news\/eventi\/indian-ceramics-asia-2023\/#article","isPartOf":{"@id":"https:\/\/bocedisrl.com\/it\/news\/eventi\/indian-ceramics-asia-2023\/"},"author":{"name":"Marco Iori","@id":"https:\/\/STRETCHHOOD.IT\/fr\/#\/schema\/person\/bf2baf56b280f94948de40b1612eae19"},"headline":"Indian Ceramics Asia 2023","datePublished":"2023-01-09T14:31:36+00:00","dateModified":"2023-01-12T13:13:46+00:00","mainEntityOfPage":{"@id":"https:\/\/bocedisrl.com\/it\/news\/eventi\/indian-ceramics-asia-2023\/"},"wordCount":358,"publisher":{"@id":"https:\/\/STRETCHHOOD.IT\/fr\/#organization"},"image":{"@id":"https:\/\/bocedisrl.com\/it\/news\/eventi\/indian-ceramics-asia-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/bocedisrl.com\/wp-content\/uploads\/2023\/01\/indian-ceramics-asia.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/bocedisrl.com\/it\/news\/eventi\/indian-ceramics-asia-2023\/","url":"https:\/\/bocedisrl.com\/it\/news\/eventi\/indian-ceramics-asia-2023\/","name":"Indian Ceramics Asia 2023 - Bocedi srl","isPartOf":{"@id":"https:\/\/STRETCHHOOD.IT\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bocedisrl.com\/it\/news\/eventi\/indian-ceramics-asia-2023\/#primaryimage"},"image":{"@id":"https:\/\/bocedisrl.com\/it\/news\/eventi\/indian-ceramics-asia-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/bocedisrl.com\/wp-content\/uploads\/2023\/01\/indian-ceramics-asia.jpg","datePublished":"2023-01-09T14:31:36+00:00","dateModified":"2023-01-12T13:13:46+00:00","breadcrumb":{"@id":"https:\/\/bocedisrl.com\/it\/news\/eventi\/indian-ceramics-asia-2023\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bocedisrl.com\/it\/news\/eventi\/indian-ceramics-asia-2023\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/bocedisrl.com\/it\/news\/eventi\/indian-ceramics-asia-2023\/#primaryimage","url":"https:\/\/bocedisrl.com\/wp-content\/uploads\/2023\/01\/indian-ceramics-asia.jpg","contentUrl":"https:\/\/bocedisrl.com\/wp-content\/uploads\/2023\/01\/indian-ceramics-asia.jpg","width":1028,"height":627},{"@type":"BreadcrumbList","@id":"https:\/\/bocedisrl.com\/it\/news\/eventi\/indian-ceramics-asia-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/STRETCHHOOD.IT\/it\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/bocedisrl.com\/it\/category\/news\/"},{"@type":"ListItem","position":3,"name":"Eventi","item":"https:\/\/bocedisrl.com\/it\/category\/news\/eventi\/"},{"@type":"ListItem","position":4,"name":"Indian Ceramics Asia 2023"}]},{"@type":"WebSite","@id":"https:\/\/STRETCHHOOD.IT\/fr\/#website","url":"https:\/\/STRETCHHOOD.IT\/fr\/","name":"Bocedi srl","description":"Pallet Packaging Systems","publisher":{"@id":"https:\/\/STRETCHHOOD.IT\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/STRETCHHOOD.IT\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/STRETCHHOOD.IT\/fr\/#organization","name":"Bocedi srl","url":"https:\/\/STRETCHHOOD.IT\/fr\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/STRETCHHOOD.IT\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.bocedisrl.com\/wp-content\/uploads\/2021\/11\/logo-bocedi.png","contentUrl":"https:\/\/www.bocedisrl.com\/wp-content\/uploads\/2021\/11\/logo-bocedi.png","width":800,"height":480,"caption":"Bocedi srl"},"image":{"@id":"https:\/\/STRETCHHOOD.IT\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/STRETCHHOOD.IT\/fr\/#\/schema\/person\/bf2baf56b280f94948de40b1612eae19","name":"Marco Iori","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/STRETCHHOOD.IT\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/619eb84d8815ffd55f76c8c96d01893a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/619eb84d8815ffd55f76c8c96d01893a?s=96&d=mm&r=g","caption":"Marco Iori"}}]}},"_links":{"self":[{"href":"https:\/\/bocedisrl.com\/it\/wp-json\/wp\/v2\/posts\/10436"}],"collection":[{"href":"https:\/\/bocedisrl.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bocedisrl.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bocedisrl.com\/it\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/bocedisrl.com\/it\/wp-json\/wp\/v2\/comments?post=10436"}],"version-history":[{"count":3,"href":"https:\/\/bocedisrl.com\/it\/wp-json\/wp\/v2\/posts\/10436\/revisions"}],"predecessor-version":[{"id":10492,"href":"https:\/\/bocedisrl.com\/it\/wp-json\/wp\/v2\/posts\/10436\/revisions\/10492"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bocedisrl.com\/it\/wp-json\/wp\/v2\/media\/10434"}],"wp:attachment":[{"href":"https:\/\/bocedisrl.com\/it\/wp-json\/wp\/v2\/media?parent=10436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bocedisrl.com\/it\/wp-json\/wp\/v2\/categories?post=10436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bocedisrl.com\/it\/wp-json\/wp\/v2\/tags?post=10436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}